{"id":4593,"date":"2013-05-13T16:20:49","date_gmt":"2013-05-13T14:20:49","guid":{"rendered":"http:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2.jpg"},"modified":"2013-05-13T16:20:49","modified_gmt":"2013-05-13T14:20:49","slug":"lisa-xtraegg2","status":"inherit","type":"attachment","link":"https:\/\/www.pierrefeuilleciseaux.com\/en\/lisa-xtraegg2\/","title":{"rendered":"LISA &#8211; xtraegg2"},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-4593","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"218\" height=\"300\" src=\"https:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2-218x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2-218x300.jpg 218w, https:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2.jpg 667w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":667,"height":916,"file":"2013\/05\/LISA-xtraegg2.jpg","sizes":{"thumbnail":{"file":"LISA-xtraegg2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2-150x150.jpg"},"medium":{"file":"LISA-xtraegg2-218x300.jpg","width":218,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2-218x300.jpg"},"full":{"file":"LISA-xtraegg2.jpg","width":667,"height":916,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":null,"source_url":"https:\/\/www.pierrefeuilleciseaux.com\/wp-content\/uploads\/2013\/05\/LISA-xtraegg2.jpg","filename":"LISA-xtraegg2.jpg","filesize":208840,"_links":{"self":[{"href":"https:\/\/www.pierrefeuilleciseaux.com\/en\/wp-json\/wp\/v2\/media\/4593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pierrefeuilleciseaux.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pierrefeuilleciseaux.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.pierrefeuilleciseaux.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pierrefeuilleciseaux.com\/en\/wp-json\/wp\/v2\/comments?post=4593"}]}}